{"id":62,"count":0,"description":"","link":"https:\/\/voe.ae\/arabic\/product-category\/professional-managment-development-training\/","name":"Professional &amp; Managment Development Training","slug":"professional-managment-development-training","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Professional &amp; Managment Development Training Archives - VOE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voe.ae\/arabic\/product-category\/professional-managment-development-training\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professional &amp; Managment Development Training Archives - VOE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voe.ae\/arabic\/product-category\/professional-managment-development-training\/\" \/>\n<meta property=\"og:site_name\" content=\"VOE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/voe.ae\\\/product-category\\\/professional-managment-development-training\\\/\",\"url\":\"https:\\\/\\\/voe.ae\\\/product-category\\\/professional-managment-development-training\\\/\",\"name\":\"Professional &amp; Managment Development Training Archives - VOE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/voe.ae\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/voe.ae\\\/product-category\\\/professional-managment-development-training\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/voe.ae\\\/product-category\\\/professional-managment-development-training\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/voe.ae\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Professional &amp; Managment Development Training\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/voe.ae\\\/#website\",\"url\":\"https:\\\/\\\/voe.ae\\\/\",\"name\":\"VOE\",\"description\":\"We provide life skills courses\",\"publisher\":{\"@id\":\"https:\\\/\\\/voe.ae\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/voe.ae\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/voe.ae\\\/#organization\",\"name\":\"VOE\",\"url\":\"https:\\\/\\\/voe.ae\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/voe.ae\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/voe.ae\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cropped-logo-voe.jpg\",\"contentUrl\":\"https:\\\/\\\/voe.ae\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/cropped-logo-voe.jpg\",\"width\":307,\"height\":80,\"caption\":\"VOE\"},\"image\":{\"@id\":\"https:\\\/\\\/voe.ae\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professional &amp; Managment Development Training Archives - VOE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voe.ae\/arabic\/product-category\/professional-managment-development-training\/","og_locale":"ar_AR","og_type":"article","og_title":"Professional &amp; Managment Development Training Archives - VOE","og_url":"https:\/\/voe.ae\/arabic\/product-category\/professional-managment-development-training\/","og_site_name":"VOE","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/voe.ae\/product-category\/professional-managment-development-training\/","url":"https:\/\/voe.ae\/product-category\/professional-managment-development-training\/","name":"Professional &amp; Managment Development Training Archives - VOE","isPartOf":{"@id":"https:\/\/voe.ae\/#website"},"breadcrumb":{"@id":"https:\/\/voe.ae\/product-category\/professional-managment-development-training\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/voe.ae\/product-category\/professional-managment-development-training\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voe.ae\/en\/"},{"@type":"ListItem","position":2,"name":"Professional &amp; Managment Development Training"}]},{"@type":"WebSite","@id":"https:\/\/voe.ae\/#website","url":"https:\/\/voe.ae\/","name":"VOE","description":"We provide life skills courses","publisher":{"@id":"https:\/\/voe.ae\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voe.ae\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/voe.ae\/#organization","name":"VOE","url":"https:\/\/voe.ae\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/voe.ae\/#\/schema\/logo\/image\/","url":"https:\/\/voe.ae\/wp-content\/uploads\/2026\/02\/cropped-logo-voe.jpg","contentUrl":"https:\/\/voe.ae\/wp-content\/uploads\/2026\/02\/cropped-logo-voe.jpg","width":307,"height":80,"caption":"VOE"},"image":{"@id":"https:\/\/voe.ae\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/voe.ae\/arabic\/wp-json\/wp\/v2\/product_cat\/62","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voe.ae\/arabic\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/voe.ae\/arabic\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/voe.ae\/arabic\/wp-json\/wp\/v2\/product?product_cat=62"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}